{"id":220,"date":"2021-09-19T14:02:50","date_gmt":"2021-09-19T14:02:50","guid":{"rendered":"https:\/\/audreym15.sg-host.com\/?page_id=220"},"modified":"2022-11-10T17:47:58","modified_gmt":"2022-11-10T17:47:58","slug":"our-commitment","status":"publish","type":"page","link":"https:\/\/tgs-france.com\/de\/our-commitment\/","title":{"rendered":"Unser Engagement"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"220\" class=\"elementor elementor-220\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-71d41b5 elementor-section-full_width elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"71d41b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0ea044 ae-bg-gallery-type-default\" data-id=\"d0ea044\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-55832d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"55832d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0cf9822 ae-bg-gallery-type-default\" data-id=\"0cf9822\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0708aa7 elementor-widget elementor-widget-heading\" data-id=\"0708aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unser Engagement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec92aea link_orange elementor-widget elementor-widget-text-editor\" data-id=\"ec92aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p dir=\"ltr\">Das TGS-Netzwerk ist seit 2017 Unterzeichner des Global Compact der Vereinten Nationen. Als TGS-Mitgliedsunternehmen verpflichten wir uns zu einer nachhaltigen Entwicklung unserer Aktivit\u00e4ten. Unser Netzwerkname und unsere Mission \"Think Global Sustainability\" stehen im Mittelpunkt unseres t\u00e4glichen Handelns.<\/p><p dir=\"ltr\">Die zehn Prinzipien des Global Compact der Vereinten Nationen stehen im Einklang mit der Politik der sozialen Verantwortung von TGS. Als TGS-Mitgliedsunternehmen konzentrieren wir uns auf Qualit\u00e4t, Vertrauensbildung und nachhaltige Beziehungen zu unseren Mitarbeitern, Kunden und Stakeholdern.<\/p><p><br \/>In einem zunehmend instabilen und unberechenbaren globalen Umfeld stellen sich st\u00e4ndig Fragen dar\u00fcber, wie wir arbeiten und wie wir die Auswirkungen unserer Gesch\u00e4ftst\u00e4tigkeit auf unsere Umwelt messen. TGS ver\u00f6ffentlicht jedes Jahr einen COP (Communication On Progress), der unser nachhaltiges Handeln dokumentiert. Sie k\u00f6nnen\u00a0<a href=\"https:\/\/www.unglobalcompact.org\/what-is-gc\/participants\/121791\" target=\"_blank\" rel=\"noopener noreferrer\">Laden Sie hier unseren neuesten COP herunter<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ab0b98e elementor-hidden-mobile ae-bg-gallery-type-default\" data-id=\"ab0b98e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6232a90 elementor-widget elementor-widget-image\" data-id=\"6232a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"606\" height=\"670\" src=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/banner-shapes-image.jpg\" class=\"attachment-large size-large wp-image-183\" alt=\"\" srcset=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/banner-shapes-image.jpg 606w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/banner-shapes-image-271x300.jpg 271w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-71c573b elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"71c573b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e984714 ae-bg-gallery-type-default\" data-id=\"e984714\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57fcc03 ae-post-layout-list link_orange elementor-widget elementor-widget-ae-post-blocks\" data-id=\"57fcc03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ae-post-blocks.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"ae-post-overlay\">\n\t\t\t\t<div class=\"ae-post-overlay-wrapper\">\n\t\t\t\t\t<div class=\"ae-post-overlay-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-sync\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"ae-post-overlay-text\">\n\t\t\t\t\t\tLaden...\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t<div data-pid=\"220\" data-wid=\"57fcc03\" data-source=\"odd\" class=\"ae-post-widget-wrapper ae-masonry- ae-hpos- ae-vpos-\">\n\t\t\n\t\t\t\t<div class=\"ae-post-list-wrapper\">\n\t\t\t\n\t\t<article class=\"ae-post-list-item ae-post-list-item-57fcc03\">\n\t\t\t<div class=\"ae-article-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-1720\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1720\" class=\"elementor elementor-1720\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-0a7b148 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"0a7b148\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-361b870 ae-bg-gallery-type-default\" data-id=\"361b870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2789758 elementor-widget elementor-widget-image\" data-id=\"2789758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-1024x1024.png\" class=\"attachment-large size-large wp-image-102\" alt=\"\" srcset=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-1024x1024.png 1024w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-300x300.png 300w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-150x150.png 150w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-768x768.png 768w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10-1536x1536.png 1536w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_10.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5906f04 ae-bg-gallery-type-default\" data-id=\"5906f04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5feb1e3 elementor-widget elementor-widget-heading\" data-id=\"5feb1e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verringerte Ungleichheiten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd5396b elementor-widget elementor-widget-text-editor\" data-id=\"dd5396b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Verringerung der Ungleichheit innerhalb und zwischen den L\u00e4ndern<\/p>\n<p>TGS France verfolgt eine sehr ehrgeizige Politik, wenn es um die Eingliederung von Menschen mit Behinderungen geht, und hat eine Reihe von Ma\u00dfnahmen in diesem Bereich eingeleitet:<\/p>\n<p>Mit seiner Tochtergesellschaft Socia3 hat TGS France stark in die Ausbildung und Eingliederung von Menschen mit Behinderungen in die Belegschaft investiert. Zur Umsetzung dieser Behindertenpolitik hat TGS Frankreich insbesondere eine Partnerschaftsvereinbarung mit Agefiph unterzeichnet, einer f\u00fchrenden Organisation f\u00fcr alle Ma\u00dfnahmen zur F\u00f6rderung der Besch\u00e4ftigung von Menschen mit Behinderungen.<\/p>\n<p>Ebenfalls im Rahmen der Agefiph-Partnerschaft hat TGS France eine <a href=\"https:\/\/www.tgs-france.fr\/actualites\/insertion-de-personne-en-situation-de-handicap-tgs-france-signe-une-convention-avec-l-agefiph\/\" target=\"_blank\" rel=\"noopener\">ein spezielles internes Schulungsprogramm f\u00fcr das Management von Behinderungen<\/a>. Dieses Programm wird auf allen Ebenen der TGS Frankreich eingesetzt.<\/p>\n<p>Mit Blick auf die Olympischen Spiele 2024 in Paris hat TGS France die erste vollst\u00e4ndig paralympische Mannschaft zusammengestellt und <a href=\"https:\/\/www.tgs-france.fr\/actualites\/tgs-france-lance-le-1er-team-d-athletes-100-parasportifs\/\" target=\"_blank\" rel=\"noopener\">sponsert f\u00fcnf behinderte Sportler<\/a> bis zu den Olympischen Spielen im Jahr 2024. Diese 5 Athleten kommen aus 5 verschiedenen Sportarten (Badminton, Radsport, Tischtennis, Tennis, Leichtathletik mit Schwerpunkt Weitsprung), mit unterschiedlichen olympischen Erfahrungen und Rekorden, mit dem gleichen Ziel: sich auf die gro\u00dfen Sportereignisse, die Olympischen Spiele 2024 in Paris, vorzubereiten und dabei zu brillieren.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-f3935fc elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"f3935fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9923c06 ae-bg-gallery-type-default\" data-id=\"9923c06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a09a657 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a09a657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\n\t\t<article class=\"ae-post-list-item ae-post-list-item-57fcc03\">\n\t\t\t<div class=\"ae-article-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-1720\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1720\" class=\"elementor elementor-1720\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-0a7b148 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"0a7b148\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-361b870 ae-bg-gallery-type-default\" data-id=\"361b870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2789758 elementor-widget elementor-widget-image\" data-id=\"2789758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3-1024x1024.png\" class=\"attachment-large size-large wp-image-2860\" alt=\"\" srcset=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3-1024x1024.png 1024w, https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3-300x300.png 300w, https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3-150x150.png 150w, https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3-768x768.png 768w, https:\/\/tgs-france.com\/wp-content\/uploads\/2022\/11\/Sustainable_Development_Goal_3.png 1536w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5906f04 ae-bg-gallery-type-default\" data-id=\"5906f04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5feb1e3 elementor-widget elementor-widget-heading\" data-id=\"5feb1e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gute Gesundheit und Wohlbefinden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd5396b elementor-widget elementor-widget-text-editor\" data-id=\"dd5396b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sicherstellung eines gesunden Lebens und F\u00f6rderung des Wohlbefindens f\u00fcr alle Menschen jeden Alters<\/p>\n<p>TGS France ist eines der Gr\u00fcndungsmitglieder der Vereinigung 1nspire, die sich zum Ziel gesetzt hat, die Gesundheit und das Wohlbefinden von Unternehmern, F\u00fchrungskr\u00e4ften und ihren Mitarbeitern als wichtigen Hebel f\u00fcr die langfristige Produktivit\u00e4t in den Vordergrund zu stellen.<\/p>\n<p>Die Gesundheit und das Wohlbefinden der Menschen, die hinter den Unternehmen stehen, sind ein enormes Potenzial f\u00fcr das Unternehmenswachstum, das jedoch noch zu oft untersch\u00e4tzt und unterbewertet wird.<\/p>\n<p>TGS France ist bestrebt, gesunde Grenzen zwischen Arbeit und Privatleben f\u00fcr alle Mitarbeiter zu setzen. Eine Burnout-Kultur (\u00dcberstunden, Dauerstress usw.) ist <strong><u>nicht<\/u><\/strong> Die Unternehmenskultur von TGS.<\/p>\n<p>Das Wohlbefinden aller Mitarbeiter, F\u00fchrungskr\u00e4fte und Mitglieder der Gesch\u00e4ftsf\u00fchrung von TGS France zu gew\u00e4hrleisten, ist eine sich st\u00e4ndig weiterentwickelnde Herausforderung.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-f3935fc elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"f3935fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9923c06 ae-bg-gallery-type-default\" data-id=\"9923c06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a09a657 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a09a657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\n\t\t<article class=\"ae-post-list-item ae-post-list-item-57fcc03\">\n\t\t\t<div class=\"ae-article-inner\">\n\t\t\t\t\t\t\t\t<div class=\"ae_data elementor elementor-1720\">\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1720\" class=\"elementor elementor-1720\" data-elementor-post-type=\"ae_global_templates\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-0a7b148 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"0a7b148\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-361b870 ae-bg-gallery-type-default\" data-id=\"361b870\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2789758 elementor-widget elementor-widget-image\" data-id=\"2789758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-1024x1024.png\" class=\"attachment-large size-large wp-image-106\" alt=\"\" srcset=\"https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-1024x1024.png 1024w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-300x300.png 300w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-150x150.png 150w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-768x768.png 768w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13-1536x1536.png 1536w, https:\/\/tgs-france.com\/wp-content\/uploads\/2021\/09\/TheGlobalGoals_Icons_Color_Goal_13.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5906f04 ae-bg-gallery-type-default\" data-id=\"5906f04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5feb1e3 elementor-widget elementor-widget-heading\" data-id=\"5feb1e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Klimama\u00dfnahmen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd5396b elementor-widget elementor-widget-text-editor\" data-id=\"dd5396b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ergreifen Sie dringend Ma\u00dfnahmen zur Bek\u00e4mpfung des Klimawandels und seiner Auswirkungen<\/p>\n<p>TGS France bem\u00fcht sich aktiv darum, seinen \u00f6kologischen Fu\u00dfabdruck zu verringern. Jede Aktion z\u00e4hlt: TGS France hat insbesondere eine Politik der Fahrgemeinschaften durchgesetzt, arbeitet an der Maximierung des Recyclings an allen Standorten und f\u00f6rdert und unterst\u00fctzt zahlreiche andere Aktionen auf lokaler Ebene.<\/p>\n<p>TGS France h\u00e4lt sich auch an alle offiziellen Richtlinien und Empfehlungen: Vor kurzem hat die franz\u00f6sische Regierung ihren Plan zur Energieeinsparung ver\u00f6ffentlicht, der eine Reihe von proaktiven Ma\u00dfnahmen enth\u00e4lt, die von Einzelpersonen und Unternehmen gleicherma\u00dfen umgesetzt werden sollen. TGS France hat den Plan sofort studiert und ihn an alle Mitarbeiter weitergegeben, um konkrete Ma\u00dfnahmen an allen TGS-Standorten umzusetzen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-f3935fc elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"f3935fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9923c06 ae-bg-gallery-type-default\" data-id=\"9923c06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a09a657 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a09a657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/article>\n\n\t\t\t\t<\/div>\n\t\t\t\t\n\n\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-f6c6201 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"f6c6201\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac50b1d ae-bg-gallery-type-default\" data-id=\"ac50b1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8783556 elementor-widget elementor-widget-text-editor\" data-id=\"8783556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00f6chten Sie mehr \u00fcber unser Fachwissen erfahren?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d1a28d1 ae-bg-gallery-type-default\" data-id=\"d1a28d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07181b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"07181b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/tgs-france.com\/de\/our-expertise\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unser Fachwissen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Our Commitment The TGS network became a signatory of the United Nations Global Compact in 2017. As a TGS member firm, we are committed to the sustainable development of our activities. Our network name and mission \u201cThink Global Sustainability\u201d is at the heart of our daily actions. The ten principles of the United Nations Global [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-220","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/pages\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":47,"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/pages\/220\/revisions"}],"predecessor-version":[{"id":2927,"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/pages\/220\/revisions\/2927"}],"wp:attachment":[{"href":"https:\/\/tgs-france.com\/de\/wp-json\/wp\/v2\/media?parent=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}